{"id":31605,"date":"2026-05-12T16:38:55","date_gmt":"2026-05-12T20:38:55","guid":{"rendered":"https:\/\/colegiomontessori.cl\/wp2\/?p=31605"},"modified":"2026-05-12T16:38:55","modified_gmt":"2026-05-12T20:38:55","slug":"administracion-cerrada-a-publico-miercoles-13-de-mayo-jornada-tarde","status":"publish","type":"post","link":"https:\/\/colegiomontessori.cl\/wp2\/2026\/05\/12\/administracion-cerrada-a-publico-miercoles-13-de-mayo-jornada-tarde\/","title":{"rendered":"Administraci\u00f3n Cerrada a P\u00fablico: Mi\u00e9rcoles 13 de Mayo (Jornada Tarde)"},"content":{"rendered":"\n<p>Estimados Padres y Apoderados,<\/p>\n\n\n\n<p>Junto con saludar informamos a Uds. que ma\u00f1ana, mi\u00e9rcoles 13 de mayo, nuestras oficinas de Administraci\u00f3n (Antonio Varas 553) se encontrar\u00e1n cerradas al p\u00fablico durante la tarde por capacitaci\u00f3n del personal, retomando la atenci\u00f3n de apoderados el d\u00eda jueves en horario habitual de 09:00 a 12:30 y de 15:00 a 17:30 horas.<\/p>\n\n\n\n<p>Atentamente,<\/p>\n\n\n\n<p><strong>Administraci\u00f3n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimados Padres y Apoderados, Junto con saludar informamos a Uds. que ma\u00f1ana, mi\u00e9rcoles 13 de mayo, nuestras oficinas de Administraci\u00f3n (Antonio Varas 553) se encontrar\u00e1n cerradas al p\u00fablico durante la tarde por capacitaci\u00f3n del personal, retomando la atenci\u00f3n de apoderados el d\u00eda jueves en horario habitual de 09:00 a 12:30 y de 15:00 a 17:30 &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/colegiomontessori.cl\/wp2\/2026\/05\/12\/administracion-cerrada-a-publico-miercoles-13-de-mayo-jornada-tarde\/\"> <span class=\"screen-reader-text\">Administraci\u00f3n Cerrada a P\u00fablico: Mi\u00e9rcoles 13 de Mayo (Jornada Tarde)<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":2,"featured_media":5906,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"class_list":["post-31605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-administracion"],"_links":{"self":[{"href":"https:\/\/colegiomontessori.cl\/wp2\/wp-json\/wp\/v2\/posts\/31605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colegiomontessori.cl\/wp2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colegiomontessori.cl\/wp2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colegiomontessori.cl\/wp2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/colegiomontessori.cl\/wp2\/wp-json\/wp\/v2\/comments?post=31605"}],"version-history":[{"count":1,"href":"https:\/\/colegiomontessori.cl\/wp2\/wp-json\/wp\/v2\/posts\/31605\/revisions"}],"predecessor-version":[{"id":31606,"href":"https:\/\/colegiomontessori.cl\/wp2\/wp-json\/wp\/v2\/posts\/31605\/revisions\/31606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colegiomontessori.cl\/wp2\/wp-json\/wp\/v2\/media\/5906"}],"wp:attachment":[{"href":"https:\/\/colegiomontessori.cl\/wp2\/wp-json\/wp\/v2\/media?parent=31605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colegiomontessori.cl\/wp2\/wp-json\/wp\/v2\/categories?post=31605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colegiomontessori.cl\/wp2\/wp-json\/wp\/v2\/tags?post=31605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}